{"id":9563,"date":"2006-01-25T00:00:00","date_gmt":"2006-01-25T00:00:00","guid":{"rendered":"http:\/\/www.mechaman.nl\/veehouderij-techniek\/?p=100257"},"modified":"2021-10-07T10:19:26","modified_gmt":"2021-10-07T08:19:26","slug":"topjaar-voor-robotfabrikanten","status":"publish","type":"post","link":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/artikel\/20060125\/topjaar-voor-robotfabrikanten\/","title":{"rendered":"Topjaar voor robotfabrikanten"},"content":{"rendered":"<p> DeLaval mocht in Denemarken in een week zelfs 25 orders noteren. Thierry Perrotin de VMS Solution Manager van VMS verwacht dat 2006 het beste jaar tot nu toe zal worden voor zijn robot. <\/p>\n<p>Ook Robot Milking Solutions (RMS), vergaat het weer goed. De dochteronderneming van Punch Technix (voorheen Prolion) heeft sinds september vorig jaar 33 multiboxsystemen van de nieuwe Titan melkrobot verkocht. Dat zijn in totaal 83 melkboxen en dat is meer dan de volledige verkoop van het boekjaar 2004-2005. Van de grootste Titan met 5 melkboxen zou RMS er al drie hebben verkocht.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.mechaman.nl\/afbeeldingen\/topjaar_robotfabrikanten_25_01_2006.jpg\" class=\"fotoinbericht\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2005 was een top jaar voor de melkrobotleveranciers Delaval, Lely en RMS. Dat blijkt uit de trotse mededelingen van bijvoorbeeld Lely die van haar net ge\u00efntroduceerde Astronaut A3 robot in zes weken maarliefst 100 stuks verkocht.<\/p>\n","protected":false},"author":3076,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wds_primary_category":0,"wds_primary_post_tag":0,"wds_primary_dossier":0,"wds_primary_artikel_type":0,"footnotes":""},"categories":[427],"tags":[],"dossier":[],"artikel_type":[27],"class_list":["post-9563","post","type-post","status-publish","format-standard","hentry","category-bedrijven","artikel_type-artikelen"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/posts\/9563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/users\/3076"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/comments?post=9563"}],"version-history":[{"count":0,"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/posts\/9563\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/media?parent=9563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/categories?post=9563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/tags?post=9563"},{"taxonomy":"dossier","embeddable":true,"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/dossier?post=9563"},{"taxonomy":"artikel_type","embeddable":true,"href":"https:\/\/www.mechaman.nl\/veehouderij-techniek\/wp-json\/wp\/v2\/artikel_type?post=9563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}